{"id":1949,"date":"2021-04-07T14:29:52","date_gmt":"2021-04-07T13:29:52","guid":{"rendered":"https:\/\/tvw-witzhelden.de\/tennis\/?page_id=1949"},"modified":"2021-04-07T15:08:18","modified_gmt":"2021-04-07T14:08:18","slug":"events","status":"publish","type":"page","link":"https:\/\/www.tvw-witzhelden.de\/tennis\/events\/","title":{"rendered":"Events"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1949\" class=\"elementor elementor-1949\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9631aa0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9631aa0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f292f84\" data-id=\"f292f84\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48584ca elementor-widget elementor-widget-heading\" data-id=\"48584ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\"><span class=\"highlight\">Events im TV Witzhelden<\/span> <\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a482ae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3a482ae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-399744b\" data-id=\"399744b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8680796 elementor-widget elementor-widget-MEC\" data-id=\"8680796\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"MEC.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mec-wrap mec-skin-grid-container  \" id=\"mec_skin_1498\">\r\n    \r\n    <div id=\"mec_search_form_1498\" class=\"mec-search-form mec-totalcal-box\"><div class=\"mec-dropdown-wrap\"><div class=\"mec-dropdown-search\"><i class=\"mec-sl-folder\"><\/i><select name=' ' id='mec_sf_category_1498' class='postform'>\n\t<option value='' selected='selected'>Kategorie<\/option>\n<\/select>\n<\/div><\/div><div class=\"mec-text-input-search\"><i class=\"mec-sl-magnifier\"><\/i>\r\n                    <input type=\"search\" value=\"\" id=\"mec_sf_s_1498\" placeholder=\"\" \/>\r\n                <\/div><\/div>    \r\n        <div class=\"mec-skin-grid-events-container\" id=\"mec_skin_events_1498\">\r\n        Keine Veranstaltung gefunden!    <\/div>\r\n        \r\n        \r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Events im TV Witzhelden KategorieCampTraining 30 April Freitag Ballmagier Details anzeigen 07 Mai Freitag Ballmagier Details anzeigen 14 Mai Freitag Ballmagier Details anzeigen 21 Mai Freitag Ballmagier Details anzeigen 24 Mai Montag TENNIS-TAGES-CAMP Details anzeigen 28 Mai Freitag Ballmagier Details anzeigen 04 Juni Freitag Ballmagier Details anzeigen 11 Juni Freitag Ballmagier Details anzeigen 18 Juni [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_mo_disable_npp":"","site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-1949","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.tvw-witzhelden.de\/tennis\/wp-json\/wp\/v2\/pages\/1949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tvw-witzhelden.de\/tennis\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.tvw-witzhelden.de\/tennis\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.tvw-witzhelden.de\/tennis\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tvw-witzhelden.de\/tennis\/wp-json\/wp\/v2\/comments?post=1949"}],"version-history":[{"count":0,"href":"https:\/\/www.tvw-witzhelden.de\/tennis\/wp-json\/wp\/v2\/pages\/1949\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.tvw-witzhelden.de\/tennis\/wp-json\/wp\/v2\/media?parent=1949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}